{"id":6979,"date":"2019-04-10T00:22:22","date_gmt":"2019-04-10T00:22:22","guid":{"rendered":"http:\/\/magazin.raiffeisen.it\/?p=6979"},"modified":"2021-12-10T17:02:42","modified_gmt":"2021-12-10T15:02:42","slug":"escursione-circolare-di-predonico","status":"publish","type":"post","link":"https:\/\/magazin.raiffeisen.it\/it\/escursione-circolare-di-predonico\/","title":{"rendered":"Escursione circolare di Predonico"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2 class=\"h2-lines\">Dati del tour<\/h2>\n<p><strong>Lunghezza:<\/strong> 14,6\u2009km<br \/>\n<strong>Tempo di percorrenza:<\/strong> 5\u2009h e 9\u2009min.<br \/>\n<strong>Salita:<\/strong> 1.023\u2009m<br \/>\n<strong>Discesa:<\/strong> 1.037\u2009m<br \/>\n<strong>Grado di difficolt\u00e0:<\/strong> medio<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.alpenvereinaktiv.com\/it\/tour\/perdonig-rundwanderung\/28252697\/\" target=\"_blank\" rel=\"noopener noreferrer\">Il tour per \u00adiPhone e \u00adAndroid<\/a>[\/vc_column_text][vc_column_text]<\/p>\n<hr class=\"green-line\" \/>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2 class=\"h2-lines\">Descrizione del percorso<\/h2>\n<p>Si parte da Appiano, \u00adseguendo le indicazioni per Castel d\u2019Appiano. Lasciata l\u2019auto dietro l\u2019albergo Kreuzstein, si imbocca il sentiero n. 546 sino al Buchwald e all\u2019Alta Via d\u2019Appiano; al bivio, si prosegue lungo la via n. 10 in direzione Predonico. Il sentiero n. 8 conduce all\u2019albergo Lipp. Seguendo la via n. 2A, si scende sin quasi a valle. A destra, il sentiero n. 2 si snoda sino a Castel d\u2019Appiano. Continuando sul Burgenweg si giunge a Castel Boymont, per poi salire lungo la via n.\u00a08A fino al serbatoio d\u2019acqua e tornare al punto di partenza.[\/vc_column_text][vc_column_text]<\/p>\n<hr class=\"green-line\" \/>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h2 class=\"h2-lines\">guida naturalistica e paesaggistica<\/h2>\n<p>\u201cSe la chiesa di San Viglio \u00e8 aperta, vale la pena entrarvi. Anche Castel d\u2019Appiano e la cappella meritano una\u00a0visita.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Olav Lutz, guida naturalistica-paesaggistica,<br \/>\n<a href=\"mailto:olav.lutz@rolmail.net\" target=\"_blank\" rel=\"noopener noreferrer\">olav.lutz@rolmail.net<\/a>[\/vc_column_text][vc_column_text]<\/p>\n<hr class=\"green-line\" \/>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer\" style=\"height:35px;clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<span class=\"initial\">Il punto<\/span> di partenza del nostro tour \u00e8 il paese di Appiano, in Oltradige. In auto, raggiungiamo Appiano Monte, parcheggiando alle spalle <a href=\"http:\/\/www.kreuzstein.com\/it\/generale\/index\/1-0.html\" target=\"_blank\" rel=\"noopener noreferrer\">dell\u2019albergo Kreuzstein<\/a>, sulla sinistra. Imboccando il sentiero n. 546, saliamo nella frescura dei faggeti sino a una radura, dove sorge l\u2019albergo Buchwald.[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h2 class=\"h2-bold\">Scenario montano mozzafiato<\/h2>\n<p>Sopra di noi, si erge imponente il Macaion, mentre ai nostri piedi si estende l\u2019ampia Valle dell\u2019Adige, sullo sfondo dell\u2019incantevole scenario dolomitico. C\u2019incamminiamo lungo l\u2019Alta Via di Appiano n. 546 e procediamo spediti sull\u2019agevole strada forestale. In prossimit\u00e0 del cartello indicante il sentiero 10A, proseguiamo in direzione Predonico, lungo il ripido sentiero boschivo che scende sino al Wieser. Imboccando il sentiero n. 8, oltrepassiamo la chiesa di San Vigilio e l\u2019omonimo colle, sino ad approdare \u00adall\u2019albergo Lipp, dove pranziamo.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<hr class=\"black-line\" \/>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2 class=\"h2-bold\">Il fenomeno naturale delle buche di ghiaccio<\/h2>\n<p>Imbocchiamo il sentiero n. 2A, che scende ripidamente (si raccomandano calzature robuste). Qui, si schiudono le porte di un \u201caltro mondo\u201d, dove l\u2019aria \u00e8 pi\u00f9 fredda e arbusti e roverelle cedono il passo a grossi massi ricoperti di muschio. Avvertiamo i flussi gelidi scorrere tra i sassi e giungiamo al monumento naturale delle conche di aria fredda, un fenomeno piuttosto ricorrente in quest\u2019area: le \u201cbuche di ghiaccio\u201d ad \u00adAppiano \u00adfunzionano secondo il medesimo principio. Prima di buscarci un raffreddore, proseguiamo la discesa, giungendo a una diramazione, dove imbocchiamo il sentiero n. 2 in direzione di Castel d\u2019Appiano. Anche qui le emozioni non mancano: passiamo accanto a una fossa di lupi ottimamente conservatasi, dove una tavola informativa illustra i dettagli della trappola. Anche in passato, i lupi erano ospiti tutt\u2019altro che graditi. Da l\u00ec a poco raggiungiamo la torre Kreideturm, una delle fortificazioni pi\u00f9 suggestive dell\u2019Alto Adige, che sorge sotto Castel d\u2019Appiano: una visita alla struttura, ampiamente restaurata, vale senza dubbio la pena. Quindi, risaliamo il sentiero Burgenweg che, in un continuo saliscendi, tra scale e gradini, ci conduce a Castel Boymont, il cui fascino medioevale \u00e8 tutt\u2019oggi percepibile. Qui, saliamo \u00adlungo la via 8A verso San Paolo e, oltrepassando un imponente serbatoio idrico, approdiamo al punto di partenza. Torniamo a casa con lo zaino pieno di immagini suggestive, che resteranno impresse a lungo nella nostra memoria.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_column_text] Dati del tour Lunghezza: 14,6\u2009km Tempo di percorrenza: 5\u2009h e 9\u2009min. Salita: 1.023\u2009m Discesa: 1.037\u2009m Grado di difficolt\u00e0: medio &nbsp; Il tour per \u00adiPhone e \u00adAndroid[\/vc_column_text][vc_column_text] [\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text] Descrizione del percorso Si parte da Appiano, \u00adseguendo le indicazioni per Castel d\u2019Appiano. Lasciata l\u2019auto dietro l\u2019albergo Kreuzstein, si imbocca il sentiero n. 546 sino [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[71],"class_list":["post-6979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli-e-svago","tag-suggerimento-di-escursione"],"_links":{"self":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/6979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/comments?post=6979"}],"version-history":[{"count":4,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/6979\/revisions"}],"predecessor-version":[{"id":9842,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/6979\/revisions\/9842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/media\/6926"}],"wp:attachment":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/media?parent=6979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/categories?post=6979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/tags?post=6979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}