{"id":11884,"date":"2023-08-07T00:26:47","date_gmt":"2023-08-06T22:26:47","guid":{"rendered":"https:\/\/magazin.raiffeisen.it\/?p=11884"},"modified":"2023-08-03T14:15:45","modified_gmt":"2023-08-03T12:15:45","slug":"leuro-diventa-digitale","status":"publish","type":"post","link":"https:\/\/magazin.raiffeisen.it\/it\/leuro-diventa-digitale\/","title":{"rendered":"L\u2019euro diventa digitale"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3 class=\"p1\"><span class=\"s1\">Che cos\u2019\u00e8 l\u2019euro digitale?<\/span><\/h3>\n<p class=\"p2\"><span class=\"s2\">Non \u00e8 una nuova valuta, ma solo la forma digitale dell\u2019euro,<\/span><span class=\"s3\"> utilizzabile al pari del denaro contante e come complemento ad esso, ma in formato virtuale.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/p>\n<p class=\"p3\"><strong><span class=\"s3\">Si tratta quindi della moneta digitale della Banca centrale europea (BCE), che ne garantisce la validit\u00e0 e il futuro utilizzo nei 19 Paesi dell\u2019Eurozona.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3 class=\"p1\"><span class=\"s1\">Quali sono i vantaggi?<\/span><\/h3>\n<p class=\"p2\"><span class=\"s2\">Gi\u00e0 oggi, molte persone preferiscono avvalersi dei sistemi di pagamento digitali e fanno sempre meno ricorso ai contanti.<\/span><span class=\"s3\"> Un euro digitale emesso dall\u2019Eurosistema rappresenta pertanto un \u201cancoraggio\u201d monetario nell\u2019era <\/span>digitale, trattandosi di un bene pubblico <span class=\"s3\">in grado aumentare l\u2019efficienza delle operazioni di pagamento e ridurre costi e l\u2019impatto ambientale, ma al contempo anche di contenere i rischi delle transazioni non regolamentate. L\u2019euro digitale \u00e8 sicuro e non \u00e8 soggetto alle fluttuazioni del mercato, perch\u00e9 sostenuto dalla BCE, al contrario delle criptovalute, dietro alle quali non esiste un\u2019entit\u00e0 identificabile che ne risponda.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>L\u2019euro digitale \u00e8 destinato ad avere successo?<\/h3>\n<p>La sua affermazione dipende dai vantaggi che offre agli utenti i quali, in base ad alcuni studi, indicano tra i pi\u00f9 importanti l\u2019ampia accettazione, la facilit\u00e0 d\u2019uso, i bassi costi, l\u2019alta velocit\u00e0, la sicurezza e la privacy. Gli esercenti, invece, ne apprezzano principalmente i costi contenuti, l\u2019usabilit\u00e0 e l\u2019integrazione con i sistemi esistenti. La configurazione dell\u2019euro digitale, attualmente in fase di elabo\u00adrazione, svolge pertanto un ruolo decisivo, poich\u00e9 deve offrire un valore aggiunto rispetto alle soluzioni esistenti.<\/p>\n<p>&nbsp;<\/p>\n<h3>Quali sono i tempi previsti?<\/h3>\n<p>La BCE sta conducendo una fase di studio che si protrarr\u00e0 fino all\u2019autunno del 2023. Quindi, sar\u00e0 la volta del Consiglio direttivo della BCE, del Parla-mento europeo e degli Stati membri, chiamati a esprimersi sull\u2019introduzione definitiva. Se si pronunceranno a favore, sar\u00e0 necessario un adegua\u00admento della legislazione europea, cui seguir\u00e0 una fase di attuazione che potrebbe durare due o tre anni. La Cassa Raiffeisen dell\u2019Alto Adige segue questo processo tramite il \u201cGruppo di Lavoro Euro digitale\u201d istituito dall\u2019ABI, cui aderisce.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Che cos\u2019\u00e8 l\u2019euro digitale? Non \u00e8 una nuova valuta, ma solo la forma digitale dell\u2019euro, utilizzabile al pari del denaro contante e come complemento ad esso, ma in formato virtuale.\u00a0 Si tratta quindi della moneta digitale della Banca centrale europea (BCE), che ne garantisce la validit\u00e0 e il futuro utilizzo nei 19 Paesi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,32],"tags":[23],"class_list":["post-11884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-titelthema","category-denaro-co","tag-pagamenti-innovativi"],"_links":{"self":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/11884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/comments?post=11884"}],"version-history":[{"count":4,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/11884\/revisions"}],"predecessor-version":[{"id":11888,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/posts\/11884\/revisions\/11888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/media\/11796"}],"wp:attachment":[{"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/media?parent=11884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/categories?post=11884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magazin.raiffeisen.it\/it\/wp-json\/wp\/v2\/tags?post=11884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}